{"id":6450,"date":"2020-07-30T12:33:39","date_gmt":"2020-07-30T12:33:39","guid":{"rendered":"https:\/\/dollmarmeccanica.com\/cms\/?page_id=6450"},"modified":"2020-08-06T09:21:23","modified_gmt":"2020-08-06T09:21:23","slug":"campi-elettromagnetici","status":"publish","type":"page","link":"https:\/\/www.dollmarmeccanica.com\/cms\/campi-elettromagnetici\/","title":{"rendered":"Campi elettromagnetici"},"content":{"rendered":"<p><\/p>\n<h4>Il <strong>D.Lgs 159\/2016<\/strong>, regolamenta gli obblighi del datore di lavoro relativi alla valutazione del rischio dell&#8217;esposizione dei lavoratori a campi elettromagnetici.<\/h4>\n<p>Il <strong>Testo Unico sulla salute e sicurezza sul lavoro<\/strong> mira a prevenire sia gli effetti biologici di tipo diretto, come il riscaldamento cutaneo, che quelli di tipo indiretto, come le interferenze con dispositivi medici impiantati sul corpo.<\/p>\n<p>In quasi tutti i luoghi di lavoro <strong>il personale pu\u00f2 essere esposto ai campi elettromagnetici.<\/strong> Qualunque\u00a0 macchinario, dispositivo o impianto alimentato ad energia elettrica emette infatti oltre a campi elettrici e magnetici anche campi elettromagnetici.<\/p>\n<p>Pertanto, se i lavoratori entrano in contatto con apparecchiature elettriche o di altra natura che possano indurre campi elettromagnetici \u00e8 obbligatorio procedere a una <strong>valutazione e misura delle eventuali implicazioni;<\/strong> a meno che le esposizioni non siano accertate come nulle o trascurabili.<\/p>\n<p>Dollmar Meccanica, grazie ad un team dedicato pu\u00f2 supportare le aziende nell&#8217;effettuare le relative misurazioni.<\/p>\n<p>[vc_row][vc_column][vc_btn title=&#8221;RICHIESTA INFORMAZIONI CAMPI ELETTROMAGNETICI&#8221; color=&#8221;info&#8221; align=&#8221;center&#8221; link=&#8221;url:mailto%3Amarketing%40dollmar.com||&#8221;][\/vc_column][\/vc_row]<\/p>","protected":false},"excerpt":{"rendered":"<p>Il D.Lgs 159\/2016, regolamenta gli obblighi del datore di lavoro relativi alla valutazione del rischio dell&#8217;esposizione dei lavoratori a campi elettromagnetici. Il Testo Unico sulla salute e sicurezza sul lavoro mira a prevenire sia gli effetti biologici di tipo diretto, come il riscaldamento cutaneo, che quelli di tipo indiretto, come le interferenze con dispositivi medici [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"parent":0,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-6450","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Campi elettromagnetici - Dollmar Meccanica S.r.l<\/title>\n<meta name=\"description\" content=\"Dollmar Meccanica offre una consulenza completa per la valutazione dell&#039;esposizione dei lavoratori ai campi elettromagnetici &gt;&gt;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dollmarmeccanica.com\/cms\/campi-elettromagnetici\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campi elettromagnetici - Dollmar Meccanica S.r.l\" \/>\n<meta property=\"og:description\" content=\"Dollmar Meccanica offre una consulenza completa per la valutazione dell&#039;esposizione dei lavoratori ai campi elettromagnetici &gt;&gt;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dollmarmeccanica.com\/cms\/campi-elettromagnetici\/\" \/>\n<meta property=\"og:site_name\" content=\"Dollmar Meccanica S.r.l\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-06T09:21:23+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.dollmarmeccanica.com\\\/cms\\\/campi-elettromagnetici\\\/\",\"url\":\"https:\\\/\\\/www.dollmarmeccanica.com\\\/cms\\\/campi-elettromagnetici\\\/\",\"name\":\"Campi elettromagnetici - Dollmar Meccanica S.r.l\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.dollmarmeccanica.com\\\/cms\\\/#website\"},\"datePublished\":\"2020-07-30T12:33:39+00:00\",\"dateModified\":\"2020-08-06T09:21:23+00:00\",\"description\":\"Dollmar Meccanica offre una consulenza completa per la valutazione dell'esposizione dei lavoratori ai campi elettromagnetici >>\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.dollmarmeccanica.com\\\/cms\\\/campi-elettromagnetici\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.dollmarmeccanica.com\\\/cms\\\/campi-elettromagnetici\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.dollmarmeccanica.com\\\/cms\\\/campi-elettromagnetici\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.dollmarmeccanica.com\\\/cms\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campi elettromagnetici\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.dollmarmeccanica.com\\\/cms\\\/#website\",\"url\":\"https:\\\/\\\/www.dollmarmeccanica.com\\\/cms\\\/\",\"name\":\"Dollmar Meccanica S.r.l\",\"description\":\"Impianti di lavaggio industriali\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.dollmarmeccanica.com\\\/cms\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.dollmarmeccanica.com\\\/cms\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.dollmarmeccanica.com\\\/cms\\\/#organization\",\"name\":\"Dollmar Meccanica\",\"url\":\"https:\\\/\\\/www.dollmarmeccanica.com\\\/cms\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.dollmarmeccanica.com\\\/cms\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dollmarmeccanica.com\\\/cms\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/logo-dollmarmeccanica-300x280_c.jpg\",\"contentUrl\":\"https:\\\/\\\/dollmarmeccanica.com\\\/cms\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/logo-dollmarmeccanica-300x280_c.jpg\",\"width\":300,\"height\":280,\"caption\":\"Dollmar Meccanica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.dollmarmeccanica.com\\\/cms\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Campi elettromagnetici - Dollmar Meccanica S.r.l","description":"Dollmar Meccanica offre una consulenza completa per la valutazione dell'esposizione dei lavoratori ai campi elettromagnetici >>","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dollmarmeccanica.com\/cms\/campi-elettromagnetici\/","og_locale":"it_IT","og_type":"article","og_title":"Campi elettromagnetici - Dollmar Meccanica S.r.l","og_description":"Dollmar Meccanica offre una consulenza completa per la valutazione dell'esposizione dei lavoratori ai campi elettromagnetici >>","og_url":"https:\/\/www.dollmarmeccanica.com\/cms\/campi-elettromagnetici\/","og_site_name":"Dollmar Meccanica S.r.l","article_modified_time":"2020-08-06T09:21:23+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.dollmarmeccanica.com\/cms\/campi-elettromagnetici\/","url":"https:\/\/www.dollmarmeccanica.com\/cms\/campi-elettromagnetici\/","name":"Campi elettromagnetici - Dollmar Meccanica S.r.l","isPartOf":{"@id":"https:\/\/www.dollmarmeccanica.com\/cms\/#website"},"datePublished":"2020-07-30T12:33:39+00:00","dateModified":"2020-08-06T09:21:23+00:00","description":"Dollmar Meccanica offre una consulenza completa per la valutazione dell'esposizione dei lavoratori ai campi elettromagnetici >>","breadcrumb":{"@id":"https:\/\/www.dollmarmeccanica.com\/cms\/campi-elettromagnetici\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dollmarmeccanica.com\/cms\/campi-elettromagnetici\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.dollmarmeccanica.com\/cms\/campi-elettromagnetici\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.dollmarmeccanica.com\/cms\/"},{"@type":"ListItem","position":2,"name":"Campi elettromagnetici"}]},{"@type":"WebSite","@id":"https:\/\/www.dollmarmeccanica.com\/cms\/#website","url":"https:\/\/www.dollmarmeccanica.com\/cms\/","name":"Dollmar Meccanica S.r.l","description":"Impianti di lavaggio industriali","publisher":{"@id":"https:\/\/www.dollmarmeccanica.com\/cms\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dollmarmeccanica.com\/cms\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.dollmarmeccanica.com\/cms\/#organization","name":"Dollmar Meccanica","url":"https:\/\/www.dollmarmeccanica.com\/cms\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.dollmarmeccanica.com\/cms\/#\/schema\/logo\/image\/","url":"https:\/\/dollmarmeccanica.com\/cms\/wp-content\/uploads\/2015\/08\/logo-dollmarmeccanica-300x280_c.jpg","contentUrl":"https:\/\/dollmarmeccanica.com\/cms\/wp-content\/uploads\/2015\/08\/logo-dollmarmeccanica-300x280_c.jpg","width":300,"height":280,"caption":"Dollmar Meccanica"},"image":{"@id":"https:\/\/www.dollmarmeccanica.com\/cms\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.dollmarmeccanica.com\/cms\/wp-json\/wp\/v2\/pages\/6450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dollmarmeccanica.com\/cms\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.dollmarmeccanica.com\/cms\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.dollmarmeccanica.com\/cms\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dollmarmeccanica.com\/cms\/wp-json\/wp\/v2\/comments?post=6450"}],"version-history":[{"count":3,"href":"https:\/\/www.dollmarmeccanica.com\/cms\/wp-json\/wp\/v2\/pages\/6450\/revisions"}],"predecessor-version":[{"id":6480,"href":"https:\/\/www.dollmarmeccanica.com\/cms\/wp-json\/wp\/v2\/pages\/6450\/revisions\/6480"}],"wp:attachment":[{"href":"https:\/\/www.dollmarmeccanica.com\/cms\/wp-json\/wp\/v2\/media?parent=6450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}